{"id":22,"date":"2024-05-31T10:53:13","date_gmt":"2024-05-31T10:53:13","guid":{"rendered":"https:\/\/dapply.agency\/?page_id=22"},"modified":"2024-06-24T07:42:40","modified_gmt":"2024-06-24T07:42:40","slug":"terms-and-conditions","status":"publish","type":"page","link":"https:\/\/dapply.agency\/de\/terms-and-conditions\/","title":{"rendered":"Bedingungen und Konditionen"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Allgemeine Bestimmungen<\/h2>\n\n\n\n<p>Indem Sie auf Dapply zugreifen und eine Bestellung aufgeben, best\u00e4tigen Sie, dass Sie mit den unten aufgef\u00fchrten Allgemeinen Gesch\u00e4ftsbedingungen einverstanden und an diese gebunden sind. Diese Bedingungen gelten f\u00fcr die gesamte Website und jede E-Mail oder Kommunikation zwischen Ihnen und Dapply.<\/p>\n\n\n\n<p>Unter keinen Umst\u00e4nden haftet das Dapply-Team f\u00fcr direkte, indirekte, besondere, zuf\u00e4llige oder Folgesch\u00e4den, einschlie\u00dflich, aber nicht beschr\u00e4nkt auf, Daten- oder Gewinnverluste, die sich aus der Nutzung oder der Unm\u00f6glichkeit der Nutzung der Materialien auf dieser Website ergeben, selbst wenn das Dapply-Team oder ein autorisierter Vertreter \u00fcber die M\u00f6glichkeit solcher Sch\u00e4den informiert wurde. Wenn die Nutzung der Materialien dieser Website eine Wartung, Reparatur oder Korrektur von Ger\u00e4ten oder Daten erfordert, \u00fcbernehmen Sie die Kosten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nutzungsrechte<\/h2>\n\n\n\n<p>Diese Allgemeinen Gesch\u00e4ftsbedingungen sind ein Vertrag zwischen Ihnen und Daply Limited (in diesen Allgemeinen Gesch\u00e4ftsbedingungen als \"Dapply\", \"uns\", \"wir\" oder \"unser\" bezeichnet), dem Anbieter der Dapply-Website (<a href=\"https:\/\/dapply.agency\/de\/\">https:\/\/dapply.agency\/<\/a>) und die von der Dapply-Website aus zug\u00e4nglichen Dienste (die in diesen Allgemeinen Gesch\u00e4ftsbedingungen zusammenfassend als \"Dapply-Dienst\" bezeichnet werden).<\/p>\n\n\n\n<p>Sie stimmen zu, an diese Bedingungen gebunden zu sein. Bitte nutzen Sie den Dapply-Service nicht, wenn Sie mit diesen Bedingungen nicht einverstanden sind. In diesen Gesch\u00e4ftsbedingungen bezieht sich der Begriff \"Sie\" auf Sie als Einzelperson und die von Ihnen vertretene Organisation. Wenn Sie gegen diese Bedingungen versto\u00dfen, behalten wir uns das Recht vor, Ihr Konto zu k\u00fcndigen oder den Zugang zu Ihrem Konto ohne Vorank\u00fcndigung zu sperren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Definitionen<\/h2>\n\n\n\n<p>F\u00fcr diese Allgemeinen Gesch\u00e4ftsbedingungen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Keks:<\/strong> Kleine Daten, die von einer Website erzeugt und von Ihrem Webbrowser gespeichert werden. Sie werden verwendet, um Ihren Browser zu identifizieren, Analysen zu erstellen und Informationen \u00fcber Sie zu speichern, wie z. B. Ihre Spracheinstellung oder Ihre Anmeldeinformationen.<\/li>\n\n\n\n<li><strong>Unternehmen:<\/strong> Wenn in dieser Richtlinie von \"Unternehmen\", \"wir\", \"uns\" oder \"unser\" die Rede ist, bezieht sich dies auf Daply Limited (Nissi, 68 Agia Napa, 5330, Famagusta, Zypern), die f\u00fcr Ihre Daten gem\u00e4\u00df diesen Allgemeinen Gesch\u00e4ftsbedingungen verantwortlich ist.<\/li>\n\n\n\n<li><strong>Land:<\/strong> In diesem Fall ist Zypern der Ort, an dem Dapply oder seine Eigent\u00fcmer\/Gr\u00fcnder ans\u00e4ssig sind.<\/li>\n\n\n\n<li><strong>Ger\u00e4t: <\/strong>Jedes mit dem Internet verbundene Ger\u00e4t, wie z. B. ein Telefon, ein Tablet, ein Computer oder ein anderes Ger\u00e4t, das zum Besuch von Dapply und zur Nutzung der Dienste verwendet werden kann.<\/li>\n\n\n\n<li><strong>Dienst:<\/strong> Bezieht sich auf die von Dapply erbrachte Dienstleistung, wie sie in den entsprechenden Bedingungen (falls verf\u00fcgbar) und auf dieser Plattform beschrieben ist.<\/li>\n\n\n\n<li><strong>Dienst von Dritten:<\/strong> Bezieht sich auf Werbetreibende, Sponsoren von Wettbewerben, Werbe- und Marketingpartner und andere, die unsere Inhalte bereitstellen oder deren Produkte oder Dienstleistungen unserer Meinung nach f\u00fcr Sie von Interesse sein k\u00f6nnten.<\/li>\n\n\n\n<li><strong>Website:<\/strong> der Website von Daply Limited, die \u00fcber diese URL aufgerufen werden kann: <a href=\"https:\/\/dapply.agency\/de\/\">https:\/\/dapply.agency\/<\/a>.<\/li>\n\n\n\n<li><strong>Sie<\/strong>: Eine nat\u00fcrliche oder juristische Person, die bei Dapply zur Nutzung der Dienste registriert ist.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Beschr\u00e4nkungen<\/h2>\n\n\n\n<p>Sie verpflichten sich, dies nicht zu tun, und Sie werden es auch anderen nicht erlauben:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Entfernen, \u00c4ndern oder Unkenntlichmachen von Eigentumshinweisen (einschlie\u00dflich Hinweisen auf Urheberrechte oder Warenzeichen) von Dapply oder seinen verbundenen Unternehmen, Partnern, Lieferanten oder den Lizenzgebern der Website.<\/li>\n\n\n\n<li>die Website oder die Plattform an Dritte zu lizenzieren, zu verkaufen, zu vermieten, zu verleasen, abzutreten, zu vertreiben, zu \u00fcbertragen, zu hosten, auszulagern, offenzulegen oder kommerziell zu nutzen.<\/li>\n\n\n\n<li>Teile der Website zu ver\u00e4ndern, davon abgeleitete Werke zu erstellen, zu disassemblieren, zu entschl\u00fcsseln, zu rekompilieren oder zur\u00fcckzuentwickeln.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Benutzer-Feedback<\/h2>\n\n\n\n<p>Jegliches Feedback, Kommentare, Ideen, Verbesserungen oder Vorschl\u00e4ge (zusammenfassend \"Vorschl\u00e4ge\"), die Sie Dapply bez\u00fcglich der Website zur Verf\u00fcgung stellen, bleiben das alleinige und exklusive Eigentum von Dapply. Dapply steht es frei, die Vorschl\u00e4ge f\u00fcr jeden Zweck und auf jede Art und Weise zu nutzen, zu kopieren, zu ver\u00e4ndern, zu ver\u00f6ffentlichen oder weiterzuverbreiten, ohne dass Sie daf\u00fcr eine Verg\u00fctung erhalten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Best\u00e4tigung der Vereinbarung<\/h2>\n\n\n\n<p>Wir haben unsere Allgemeinen Gesch\u00e4ftsbedingungen aktualisiert, um vollst\u00e4ndige Transparenz dar\u00fcber zu schaffen, was beim Besuch unserer Website festgelegt wird und wie es verwendet wird. Durch die Nutzung unserer Website, die Registrierung eines Kontos oder den Kauf erkl\u00e4ren Sie sich jetzt mit unseren Gesch\u00e4ftsbedingungen einverstanden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aktualisierungen unserer Allgemeinen Gesch\u00e4ftsbedingungen<\/h2>\n\n\n\n<p>Sie erkennen an und erkl\u00e4ren sich damit einverstanden, dass Dapply nach eigenem Ermessen und ohne vorherige Ank\u00fcndigung die Bereitstellung der Dienstleistung (oder jeglicher Funktionen innerhalb der Dienstleistung) f\u00fcr Sie oder Nutzer (dauerhaft oder vor\u00fcbergehend) einstellen kann. Sie k\u00f6nnen die Nutzung des Dienstes jederzeit einstellen. Sie brauchen Dapply nicht zu informieren, wenn Sie die Nutzung des Dienstes einstellen. Sie nehmen zur Kenntnis und erkl\u00e4ren sich damit einverstanden, dass Sie im Falle einer Deaktivierung des Zugangs zu Ihrem Konto durch Dapply daran gehindert werden k\u00f6nnen, auf die Dienstleistung, Ihre Kontodaten oder auf Dateien oder andere in Ihrem Konto enthaltene Materialien zuzugreifen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c4nderungen der Website<\/h2>\n\n\n\n<p>Dapply beh\u00e4lt sich das Recht vor, die Website oder jeden Dienst, mit dem sie verbunden ist, mit oder ohne Vorank\u00fcndigung und ohne Haftung Ihnen gegen\u00fcber vor\u00fcbergehend oder dauerhaft zu \u00e4ndern, auszusetzen oder einzustellen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00dcberarbeitung der Website<\/h2>\n\n\n\n<p>Dapply kann von Zeit zu Zeit Erweiterungen oder Verbesserungen an den Merkmalen\/Funktionen der Website vornehmen, die Patches, Fehlerbehebungen, Updates, Upgrades und andere \u00c4nderungen (\"Updates\") umfassen k\u00f6nnen. Updates k\u00f6nnen bestimmte Merkmale und\/oder Funktionen der Website \u00e4ndern oder l\u00f6schen. Sie erkl\u00e4ren sich damit einverstanden, dass Dapply nicht verpflichtet ist, (i) Updates zur Verf\u00fcgung zu stellen oder (ii) bestimmte Merkmale und\/oder Funktionen der Website weiterhin f\u00fcr Sie bereitzustellen oder zu aktivieren. Sie erkl\u00e4ren sich ferner damit einverstanden, dass alle Updates (i) als integraler Bestandteil der Website angesehen werden und (ii) den Bedingungen dieser Vereinbarung unterliegen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Externe Dienstleistungen<\/h2>\n\n\n\n<p>Wir k\u00f6nnen Inhalte von Drittanbietern (einschlie\u00dflich Daten, Informationen, Anwendungen und andere Produkte und Dienstleistungen) anzeigen, einbeziehen oder zur Verf\u00fcgung stellen oder Links zu Websites oder Dienstleistungen von Drittanbietern anbieten (\"Dienstleistungen von Drittanbietern\"). Sie nehmen zur Kenntnis und erkl\u00e4ren sich damit einverstanden, dass Dapply keine Verantwortung f\u00fcr die Dienste Dritter \u00fcbernimmt, einschlie\u00dflich deren Richtigkeit, Vollst\u00e4ndigkeit, Aktualit\u00e4t, G\u00fcltigkeit, Einhaltung des Urheberrechts, Rechtm\u00e4\u00dfigkeit, Anstand, Qualit\u00e4t oder andere Aspekte davon.<\/p>\n\n\n\n<p>Dapply \u00fcbernimmt keine Haftung oder Verantwortung gegen\u00fcber Ihnen oder einer anderen nat\u00fcrlichen oder juristischen Person f\u00fcr Dienstleistungen Dritter. Die Dienste Dritter und die Links zu ihnen werden ausschlie\u00dflich zu Ihrer Bequemlichkeit zur Verf\u00fcgung gestellt, und Sie greifen auf sie zu und nutzen sie ausschlie\u00dflich auf Ihr eigenes Risiko und vorbehaltlich der Bedingungen und Konditionen dieser Drittparteien.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dauer und Beendigung<\/h2>\n\n\n\n<p>Diese Vereinbarung bleibt in Kraft, bis Sie oder Dapply sie k\u00fcndigen. Dapply kann nach eigenem Ermessen diese Vereinbarung mit oder ohne vorherige Ank\u00fcndigung jederzeit und ohne Angabe von Gr\u00fcnden aussetzen oder k\u00fcndigen. Diese Vereinbarung wird sofort und ohne vorherige Ank\u00fcndigung von Dapply beendet, wenn Sie eine Bestimmung dieser Vereinbarung nicht einhalten. Sie k\u00f6nnen diese Vereinbarung auch k\u00fcndigen, indem Sie die Website und alle Kopien von Ihrem Computer l\u00f6schen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ausschluss von Garantien<\/h2>\n\n\n\n<p>Die Website wird Ihnen \"WIE BESTEHEND\" und \"WIE VERF\u00dcGBAR\" zur Verf\u00fcgung gestellt und weist alle Fehler und M\u00e4ngel ohne jegliche Garantie auf. Im gr\u00f6\u00dftm\u00f6glichen Umfang, der nach geltendem Recht zul\u00e4ssig ist, lehnt Dapply in seinem Namen und im Namen seiner Tochtergesellschaften und deren jeweiligen Lizenzgebern und Dienstleistern ausdr\u00fccklich alle ausdr\u00fccklichen, stillschweigenden, gesetzlichen oder anderweitigen Garantien in Bezug auf die Website ab, einschlie\u00dflich aller stillschweigenden Garantien der Marktg\u00e4ngigkeit, der Eignung f\u00fcr einen bestimmten Zweck, des Eigentumsrechts und der Nichtverletzung von Rechten Dritter sowie Garantien, die sich aus dem Gesch\u00e4ftsverlauf, der Leistungserbringung, der Nutzung oder der Handelspraxis ergeben k\u00f6nnen. Ohne Einschr\u00e4nkung des Vorstehenden \u00fcbernimmt Dapply keine Garantie oder Verpflichtung und gibt keinerlei Zusicherungen ab, dass die Website Ihren Anforderungen entspricht, die beabsichtigten Ergebnisse erzielt, mit anderer Software, Systemen oder Dienstleistungen kompatibel ist oder zusammenarbeitet, ohne Unterbrechung funktioniert, Leistungs- oder Zuverl\u00e4ssigkeitsstandards erf\u00fcllt oder fehlerfrei ist oder dass Fehler oder M\u00e4ngel korrigiert werden k\u00f6nnen oder werden.<\/p>\n\n\n\n<p>Ohne das Vorstehende einzuschr\u00e4nken, geben weder Dapply noch ein Dapply-Anbieter eine ausdr\u00fcckliche oder stillschweigende Zusicherung oder Gew\u00e4hrleistung jeglicher Art: (i) in Bezug auf den Betrieb oder die Verf\u00fcgbarkeit der Website oder der darin enthaltenen Informationen, Inhalte und Materialien oder Produkte; (ii) dass die Website ununterbrochen oder fehlerfrei funktioniert; (iii) in Bezug auf die Genauigkeit, Zuverl\u00e4ssigkeit oder Aktualit\u00e4t von Informationen oder Inhalten, die \u00fcber die Website bereitgestellt werden; oder (iv) dass die Website, ihre Server, die Inhalte oder E-Mails, die von oder im Namen von Dapply gesendet werden, frei von Viren, Skripten, Trojanern, W\u00fcrmern, Malware, Zeitbomben oder anderen sch\u00e4dlichen Komponenten sind. Einige Gerichtsbarkeiten lassen den Ausschluss oder die Beschr\u00e4nkung von stillschweigenden Garantien oder die geltenden gesetzlichen Rechte eines Verbrauchers nicht zu, so dass einige oder alle der oben genannten Ausschl\u00fcsse und Beschr\u00e4nkungen m\u00f6glicherweise nicht auf Sie zutreffen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Haftungsh\u00f6chstbetr\u00e4ge<\/h2>\n\n\n\n<p>Ungeachtet etwaiger Sch\u00e4den, die Ihnen entstehen k\u00f6nnten, ist die gesamte Haftung von Dapply und seinen Zulieferern im Rahmen dieser Vereinbarung und Ihr ausschlie\u00dflicher Rechtsbehelf in Bezug auf alle vorgenannten Punkte auf den von Ihnen f\u00fcr die Website gezahlten Betrag beschr\u00e4nkt. Soweit es das geltende Recht zul\u00e4sst, sind Dapply oder seine Lieferanten in keinem Fall haftbar f\u00fcr besondere, zuf\u00e4llige, indirekte oder Folgesch\u00e4den (einschlie\u00dflich, aber nicht beschr\u00e4nkt auf Sch\u00e4den durch Gewinnverlust, Verlust von Daten oder anderen Informationen, Gesch\u00e4ftsunterbrechung, Personensch\u00e4den, f\u00fcr den Verlust der Privatsph\u00e4re, die sich aus der Nutzung oder der Unm\u00f6glichkeit der Nutzung der Website, der Software von Dritten und\/oder der Hardware von Dritten, die mit der Website verwendet wird, oder in sonstiger Weise in Verbindung mit einer Bestimmung dieser Vereinbarung ergeben), selbst wenn Dapply oder ein Lieferant auf die M\u00f6glichkeit solcher Sch\u00e4den hingewiesen wurde und selbst wenn die Abhilfe ihren wesentlichen Zweck verfehlt. Einige Gerichtsbarkeiten lassen den Ausschluss oder die Beschr\u00e4nkung von zuf\u00e4lligen oder Folgesch\u00e4den nicht zu, so dass die obige Beschr\u00e4nkung oder der Ausschluss f\u00fcr Sie m\u00f6glicherweise nicht gilt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Entsch\u00e4digung f\u00fcr Sch\u00e4den<\/h2>\n\n\n\n<p>Sie erkl\u00e4ren sich damit einverstanden, Dapply und seine Muttergesellschaften, Tochtergesellschaften, verbundenen Unternehmen, leitenden Angestellten, Mitarbeiter, Vertreter, Partner und Lizenzgeber (falls vorhanden) schadlos zu halten von jeglichen Anspr\u00fcchen oder Forderungen, einschlie\u00dflich angemessener Anwaltskosten, die aufgrund von oder in Zusammenhang mit Ihrer: (a) der Nutzung der Website; (b) der Verletzung dieser Vereinbarung oder eines Gesetzes oder einer Vorschrift; oder (c) der Verletzung eines Rechts eines Dritten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Teilweise Invalidit\u00e4t<\/h2>\n\n\n\n<p>Zusammen mit den Datenschutzrichtlinien und anderen rechtlichen Hinweisen, die von Dapply auf den Dienstleistungen ver\u00f6ffentlicht werden, stellt diese Vereinbarung die gesamte Vereinbarung zwischen Ihnen und Dapply bez\u00fcglich der Dienstleistungen dar. Angenommen, eine Bestimmung dieser Vereinbarung wird von einem zust\u00e4ndigen Gericht f\u00fcr ung\u00fcltig erkl\u00e4rt. In diesem Fall ber\u00fchrt die Ung\u00fcltigkeit einer solchen Bestimmung nicht die G\u00fcltigkeit der \u00fcbrigen Bestimmungen dieser Vereinbarung, die in vollem Umfang in Kraft bleiben. Ein Verzicht auf eine Bestimmung dieser Vereinbarung gilt nicht als weiterer oder dauerhafter Verzicht auf diese oder eine andere Bestimmung. Das Vers\u00e4umnis von Dapply, ein Recht oder eine Bestimmung aus dieser Vereinbarung geltend zu machen, stellt keinen Verzicht auf dieses Recht oder diese Bestimmung dar. Sie und Dapply vereinbaren, dass jeder Klagegrund, der sich aus oder im Zusammenhang mit den Dienstleistungen ergibt, innerhalb eines (1) Jahres nach Auftreten des Klagegrundes beginnen muss. Andernfalls ist ein solcher Klagegrund dauerhaft verj\u00e4hrt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Verzicht auf Rechte<\/h2>\n\n\n\n<p>Sofern hierin nichts anderes bestimmt ist, hat das Vers\u00e4umnis, ein Recht auszu\u00fcben oder die Erf\u00fcllung einer Verpflichtung im Rahmen dieser Vereinbarung zu verlangen, keine Auswirkungen auf die F\u00e4higkeit einer Partei, dieses Recht auszu\u00fcben oder diese Erf\u00fcllung zu irgendeinem sp\u00e4teren Zeitpunkt zu verlangen, noch stellt der Verzicht auf eine Verletzung einen Verzicht auf eine sp\u00e4tere Verletzung dar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vollst\u00e4ndige Vereinbarung<\/h2>\n\n\n\n<p>Die Vereinbarung stellt die gesamte Vereinbarung zwischen Ihnen und Dapply in Bezug auf Ihre Nutzung der Website dar und ersetzt alle vorherigen und gleichzeitigen schriftlichen oder m\u00fcndlichen Vereinbarungen zwischen Ihnen und Dapply.&nbsp;<\/p>\n\n\n\n<p>Es kann sein, dass Sie zus\u00e4tzlichen Bedingungen unterliegen, wenn Sie andere Dapply-Dienste nutzen oder kaufen, die Dapply Ihnen zum Zeitpunkt der Nutzung oder des Kaufs mitteilt.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c4nderungen des Abkommens<\/h2>\n\n\n\n<p>Dapply beh\u00e4lt sich das Recht vor, diese Vereinbarung jederzeit zu \u00e4ndern oder zu ersetzen. Wenn eine \u00c4nderung wesentlich ist, werden wir Sie mindestens 30 Tage vorher informieren, bevor die neuen Bedingungen in Kraft treten. Was eine wesentliche \u00c4nderung darstellt, wird nach unserem alleinigen Ermessen bestimmt.&nbsp;<\/p>\n\n\n\n<p>Indem Sie nach Inkrafttreten von \u00c4nderungen weiterhin auf unsere Website zugreifen oder sie nutzen, erkl\u00e4ren Sie sich mit den \u00fcberarbeiteten Bedingungen einverstanden. Wenn Sie mit den neuen Bedingungen nicht einverstanden sind, k\u00f6nnen Sie Dapply nicht mehr nutzen.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Eigentum an den Inhalten<\/h2>\n\n\n\n<p>Die Website und ihr gesamter Inhalt, ihre Eigenschaften und ihre Funktionalit\u00e4t (einschlie\u00dflich, aber nicht beschr\u00e4nkt auf alle Informationen, Software, Texte, Anzeigen, Bilder, Videos und Audios sowie deren Design, Auswahl und Anordnung) sind Eigentum von Dapply, seinen Lizenzgebern oder anderen Anbietern dieses Materials. Sie sind durch die internationalen Urheberrechts-, Marken-, Patent-, Gesch\u00e4ftsgeheimnis- und andere Gesetze zum Schutz des geistigen Eigentums oder der Eigentumsrechte gesch\u00fctzt. Das Material darf ohne die ausdr\u00fcckliche vorherige schriftliche Genehmigung von Dapply weder ganz noch teilweise kopiert, ver\u00e4ndert, vervielf\u00e4ltigt, heruntergeladen oder in irgendeiner Weise verbreitet werden, es sei denn, dies ist ausdr\u00fccklich in diesen Nutzungsbedingungen vorgesehen. Jede unbefugte Nutzung des Materials ist verboten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Schiedsgerichtsvereinbarung<\/h2>\n\n\n\n<p>Dieser Abschnitt gilt f\u00fcr alle Streitigkeiten, mit der Ausnahme von Streitigkeiten im Zusammenhang mit Unterlassungsanspr\u00fcchen oder Billigkeitsanspr\u00fcchen in Bezug auf die Durchsetzung oder G\u00fcltigkeit Ihrer oder der geistigen Eigentumsrechte von dapply.<\/p>\n\n\n\n<p>Der Begriff \"Streitfall\" bezieht sich auf alle Streitigkeiten, Klagen oder andere Kontroversen zwischen Ihnen und Dapply in Bezug auf die Dienstleistungen oder diese Vereinbarung, unabh\u00e4ngig davon, ob sie auf einem Vertrag, einer Garantie, einer unerlaubten Handlung, einem Gesetz, einer Verordnung oder einer anderen rechtlichen oder gerechten Grundlage beruhen. Der Begriff \"Streitfall\" erh\u00e4lt die weitestm\u00f6gliche Bedeutung, die nach dem Gesetz zul\u00e4ssig ist.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Obligatorische Schiedsgerichtsbarkeit<\/h2>\n\n\n\n<p>Angenommen, Sie und Dapply k\u00f6nnen eine Streitigkeit nicht durch informelle Verhandlungen beilegen. In diesem Fall werden alle weiteren Bem\u00fchungen zur Beilegung der Streitigkeit ausschlie\u00dflich durch ein verbindliches Schiedsverfahren, wie in diesem Abschnitt beschrieben, durchgef\u00fchrt. Sie verzichten auf das Recht, alle Streitigkeiten vor Gericht vor einem Richter oder einer Jury zu verhandeln (oder als Partei oder Gruppenmitglied teilzunehmen).<\/p>\n\n\n\n<p>Die Streitigkeit wird durch ein verbindliches Schiedsverfahren nach der zypriotischen Handelsschiedsgerichtsordnung beigelegt. Jede Partei kann bei jedem zust\u00e4ndigen Gericht eine einstweilige oder vorl\u00e4ufige Verf\u00fcgung beantragen, wenn dies zum Schutz der Rechte oder des Eigentums der Partei bis zum Abschluss des Schiedsverfahrens erforderlich ist. Die nicht obsiegende Partei tr\u00e4gt alle der obsiegenden Partei entstandenen Anwalts-, Rechnungslegungs- und sonstigen Kosten, Geb\u00fchren und Auslagen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Benachrichtigung bei Streitigkeiten<\/h2>\n\n\n\n<p>Im Falle einer Streitigkeit m\u00fcssen Sie oder Dapply der anderen Partei eine Streitanzeige zukommen lassen, eine schriftliche Erkl\u00e4rung, die den Namen, die Adresse und die Kontaktinformationen der Partei, die sie abgibt, den Sachverhalt, der Anlass f\u00fcr die Streitigkeit ist, und die geforderte Abhilfe enth\u00e4lt. Sie m\u00fcssen jede Streitanzeige per E-Mail an folgende Adresse senden <a href=\"mailto:info@dapply.agency\">info@dapply.agency<\/a>. Dapply sendet Ihnen eine Streitbeilegungsmitteilung per Post an Ihre Adresse, wenn wir diese haben, oder andernfalls an Ihre E-Mail-Adresse. Sie und Dapply werden versuchen, jede Streitigkeit durch informelle Verhandlungen innerhalb von sechzig (60) Tagen ab dem Datum der Mitteilung der Streitigkeit zu l\u00f6sen. Nach sechzig (60) Tagen k\u00f6nnen Sie oder Dapply ein Schiedsverfahren einleiten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Daten und Datenschutz<\/h2>\n\n\n\n<p>Wenn Sie Ideen, kreative Vorschl\u00e4ge, Entw\u00fcrfe, Fotos, Informationen, Werbung, Daten oder Vorschl\u00e4ge, einschlie\u00dflich Ideen f\u00fcr neue oder verbesserte Produkte, Dienstleistungen, Funktionen, Technologien oder Werbeaktionen, einreichen oder ver\u00f6ffentlichen, erkl\u00e4ren Sie sich ausdr\u00fccklich damit einverstanden, dass solche Einsendungen automatisch als nicht vertraulich und nicht urheberrechtlich gesch\u00fctzt behandelt werden und in das alleinige Eigentum von Dapply \u00fcbergehen, ohne dass Sie daf\u00fcr entsch\u00e4digt werden oder eine Anerkennung erhalten. Dapply und seine Partner haben keine Verpflichtungen bez\u00fcglich solcher Einsendungen oder Beitr\u00e4ge. Sie k\u00f6nnen die Ideen, die in solchen Einsendungen oder Beitr\u00e4gen enthalten sind, f\u00fcr beliebige Zwecke in jedem Medium auf unbestimmte Zeit verwenden, einschlie\u00dflich, aber nicht beschr\u00e4nkt auf die Entwicklung, Herstellung und Vermarktung von Produkten und Dienstleistungen, die solche Ideen verwenden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Angebote und Wettbewerbe<\/h2>\n\n\n\n<p>Dapply kann gelegentlich Wettbewerbe, Promotionen, Gewinnspiele oder andere Aktivit\u00e4ten (\"Promotionen\") anbieten, bei denen Sie Material oder Informationen \u00fcber sich selbst einreichen m\u00fcssen. Bitte beachten Sie, dass alle Aktionen gesonderten Regeln unterliegen k\u00f6nnen, die bestimmte Teilnahmebedingungen enthalten, wie z. B. Einschr\u00e4nkungen hinsichtlich des Alters und des geografischen Standorts. Sie sind daf\u00fcr verantwortlich, alle Regeln f\u00fcr Werbeaktionen zu lesen, um festzustellen, ob Sie zur Teilnahme berechtigt sind oder nicht. Wenn Sie an einer Werbeaktion teilnehmen, erkl\u00e4ren Sie sich damit einverstanden, alle Regeln der Werbeaktion zu befolgen und einzuhalten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Berichtigung von Fehlern<\/h2>\n\n\n\n<p>Wenn ein Produkt und\/oder eine Dienstleistung aufgrund eines Tippfehlers zu einem falschen Preis oder mit falschen Informationen aufgef\u00fchrt wird, haben wir das Recht, alle Bestellungen f\u00fcr das Produkt und\/oder die Dienstleistung, die zu dem falschen Preis aufgef\u00fchrt sind, abzulehnen oder zu stornieren. Wir haben das Recht, eine solche Bestellung abzulehnen oder zu stornieren, unabh\u00e4ngig davon, ob die Bestellung best\u00e4tigt und Ihre Kreditkarte belastet wurde oder nicht. Wenn Ihre Kreditkarte bereits f\u00fcr den Kauf belastet wurde und Ihre Bestellung storniert wird, werden wir unverz\u00fcglich eine Gutschrift auf Ihr Kreditkartenkonto oder andere Zahlungskonten in H\u00f6he der Belastung vornehmen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Allgemeiner Haftungsausschluss<\/h2>\n\n\n\n<p>Dapply ist nicht verantwortlich f\u00fcr den Inhalt, den Code oder andere Ungenauigkeiten. Dapply gibt keine Garantien oder Zusicherungen. In keinem Fall haftet Dapply f\u00fcr besondere, direkte, indirekte oder zuf\u00e4llige Sch\u00e4den oder Sch\u00e4den jeglicher Art, sei es durch Vertrag, Fahrl\u00e4ssigkeit oder andere unerlaubte Handlungen, die aus oder in Verbindung mit der Nutzung des Dienstes oder der Inhalte des Dienstes entstehen.<\/p>\n\n\n\n<p>Dapply beh\u00e4lt sich das Recht vor, den Inhalt des Dienstes jederzeit und ohne vorherige Ank\u00fcndigung zu erg\u00e4nzen, zu l\u00f6schen oder zu \u00e4ndern. Der Dapply-Service und seine Inhalte werden \"wie sie sind\" und \"wie verf\u00fcgbar\" ohne jegliche ausdr\u00fcckliche oder stillschweigende Garantie oder Zusicherung bereitgestellt. Dapply ist ein Verteiler und kein Herausgeber von Inhalten, die von Dritten bereitgestellt werden; als solcher \u00fcbt Dapply keine redaktionelle Kontrolle \u00fcber diese Inhalte aus und gibt keine Garantie oder Zusicherung hinsichtlich der Genauigkeit, Zuverl\u00e4ssigkeit oder Aktualit\u00e4t von Informationen, Inhalten, Dienstleistungen oder Waren, die \u00fcber den Dapply-Service bereitgestellt werden oder \u00fcber diesen zug\u00e4nglich sind.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Kontakt aufnehmen<\/h2>\n\n\n\n<p>Wenn Sie Fragen haben, wenden Sie sich bitte an uns:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Per E-Mail an <a href=\"mailto:info@dapply.agency\">info@dapply.agency<\/a>;<\/li>\n\n\n\n<li>Telefonisch unter <a href=\"tel:  35724030352\">+35724030352<\/a>;<\/li>\n\n\n\n<li>Oder \u00fcber das Kontaktformular auf der Website: <a href=\"https:\/\/dapply.agency\/de\/get-in-touch\/\">https:\/\/dapply.agency\/get-in-touch\/<\/a>.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Overall Provisions By accessing and placing an order with Dapply, you confirm that you are in agreement with and bound by the terms of service in the Terms and Conditions outlined below. These terms apply to the entire website and any email or communication between you and Dapply. Under no circumstances shall the Dapply team [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-pages\/policy.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-22","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Terms and Conditions - Dapply agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dapply.agency\/de\/terms-and-conditions\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms and Conditions - Dapply agency\" \/>\n<meta property=\"og:description\" content=\"Overall Provisions By accessing and placing an order with Dapply, you confirm that you are in agreement with and bound by the terms of service in the Terms and Conditions outlined below. These terms apply to the entire website and any email or communication between you and Dapply. Under no circumstances shall the Dapply team [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dapply.agency\/de\/terms-and-conditions\/\" \/>\n<meta property=\"og:site_name\" content=\"Dapply agency\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-24T07:42:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dapply.agency\/terms-and-conditions\/\",\"url\":\"https:\/\/dapply.agency\/terms-and-conditions\/\",\"name\":\"Terms and Conditions - Dapply agency\",\"isPartOf\":{\"@id\":\"https:\/\/dapply.agency\/#website\"},\"datePublished\":\"2024-05-31T10:53:13+00:00\",\"dateModified\":\"2024-06-24T07:42:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dapply.agency\/terms-and-conditions\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dapply.agency\/terms-and-conditions\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dapply.agency\/terms-and-conditions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dapply.agency\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms and Conditions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dapply.agency\/#website\",\"url\":\"https:\/\/dapply.agency\/\",\"name\":\"Dapply agency\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dapply.agency\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terms and Conditions - Dapply agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dapply.agency\/de\/terms-and-conditions\/","og_locale":"de_DE","og_type":"article","og_title":"Terms and Conditions - Dapply agency","og_description":"Overall Provisions By accessing and placing an order with Dapply, you confirm that you are in agreement with and bound by the terms of service in the Terms and Conditions outlined below. These terms apply to the entire website and any email or communication between you and Dapply. Under no circumstances shall the Dapply team [&hellip;]","og_url":"https:\/\/dapply.agency\/de\/terms-and-conditions\/","og_site_name":"Dapply agency","article_modified_time":"2024-06-24T07:42:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dapply.agency\/terms-and-conditions\/","url":"https:\/\/dapply.agency\/terms-and-conditions\/","name":"Terms and Conditions - Dapply agency","isPartOf":{"@id":"https:\/\/dapply.agency\/#website"},"datePublished":"2024-05-31T10:53:13+00:00","dateModified":"2024-06-24T07:42:40+00:00","breadcrumb":{"@id":"https:\/\/dapply.agency\/terms-and-conditions\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dapply.agency\/terms-and-conditions\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dapply.agency\/terms-and-conditions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dapply.agency\/"},{"@type":"ListItem","position":2,"name":"Terms and Conditions"}]},{"@type":"WebSite","@id":"https:\/\/dapply.agency\/#website","url":"https:\/\/dapply.agency\/","name":"Dapply agency","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dapply.agency\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/dapply.agency\/de\/wp-json\/wp\/v2\/pages\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dapply.agency\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dapply.agency\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dapply.agency\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dapply.agency\/de\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":4,"href":"https:\/\/dapply.agency\/de\/wp-json\/wp\/v2\/pages\/22\/revisions"}],"predecessor-version":[{"id":314,"href":"https:\/\/dapply.agency\/de\/wp-json\/wp\/v2\/pages\/22\/revisions\/314"}],"wp:attachment":[{"href":"https:\/\/dapply.agency\/de\/wp-json\/wp\/v2\/media?parent=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}