{"id":19,"date":"2024-05-31T09:59:57","date_gmt":"2024-05-31T09:59:57","guid":{"rendered":"https:\/\/dapply.agency\/?page_id=19"},"modified":"2024-06-24T07:42:25","modified_gmt":"2024-06-24T07:42:25","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/dapply.agency\/it\/privacy-policy\/","title":{"rendered":"Informativa sulla privacy"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Introduzione<\/h2>\n\n\n\n<p>Dapply (\"noi\", \"nostro\" o \"ci\") si impegna a proteggere la vostra privacy. La presente Informativa sulla privacy spiega come Dapply raccoglie, utilizza e divulga i vostri dati personali.<\/p>\n\n\n\n<p>Accedendo o utilizzando il nostro Servizio, l'utente dichiara di aver letto, compreso e accettato la raccolta, l'archiviazione, l'utilizzo e la divulgazione dei suoi dati personali come descritto nella presente Informativa sulla privacy.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Definizioni e termini chiave<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Biscotto:<\/strong> Un piccolo dato generato da un sito web e salvato dal browser. Viene utilizzato per identificare il browser, fornire analisi e ricordare informazioni sull'utente, come la lingua preferita o le informazioni di accesso.<\/li>\n\n\n\n<li><strong>Azienda:<\/strong> Quando in questa informativa si parla di \"Azienda\", \"noi\" o \"nostro\", ci si riferisce a Daply Limited (Nissi, 68 Agia Napa, 5330, Famagosta, Cipro), responsabile delle informazioni dell'utente ai sensi della presente Informativa sulla privacy.<\/li>\n\n\n\n<li><strong>Paese:<\/strong> La sede di Dapply o dei proprietari\/fondatori di Dapply, in questo caso, \u00e8 Cipro.<\/li>\n\n\n\n<li><strong>Cliente:<\/strong> Si riferisce all'azienda, all'organizzazione o alla persona che si iscrive al Servizio Dapply per gestire le relazioni con i vostri consumatori o utenti del servizio.<\/li>\n\n\n\n<li><strong>Dispositivo: <\/strong>Qualsiasi dispositivo connesso a Internet, come un telefono, un tablet, un computer o un altro dispositivo che possa essere utilizzato per visitare Dapply e utilizzare i servizi.<\/li>\n\n\n\n<li><strong>Indirizzo IP:<\/strong> A ogni dispositivo connesso a Internet viene assegnato un numero noto come indirizzo di protocollo Internet (IP). Questi numeri sono solitamente assegnati in blocchi geografici. Un indirizzo IP pu\u00f2 spesso identificare la posizione da cui un dispositivo si connette a Internet.<\/li>\n\n\n\n<li><strong>Personale<\/strong>: Si riferisce a coloro che sono impiegati da Dapply o sono sotto contratto per eseguire un servizio per conto di una delle parti.<\/li>\n\n\n\n<li><strong>Dati personali:<\/strong> Qualsiasi informazione che direttamente, indirettamente o in connessione con altre informazioni - compreso un numero di identificazione personale - consenta l'identificazione o l'identificabilit\u00e0 di una persona fisica.<\/li>\n\n\n\n<li><strong>Servizio:<\/strong> Si riferisce al servizio fornito da Dapply come descritto nelle relative condizioni (se disponibili) e su questa piattaforma.<\/li>\n\n\n\n<li><strong>Servizio di terze parti:<\/strong> Si riferisce a inserzionisti, sponsor di concorsi, partner promozionali e di marketing e altri soggetti che forniscono i nostri contenuti o i cui prodotti o servizi riteniamo possano interessarvi. Sito web: Il sito di Illumina Solutions LTD, accessibile tramite questo URL: <a href=\"https:\/\/dapply.agency\/it\/\">https:\/\/dapply.agency\/<\/a>.<\/li>\n\n\n\n<li><strong>Tu: <\/strong>Una persona o un'entit\u00e0 registrata presso Dapply per utilizzare i Servizi.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Quali informazioni raccogliamo?<\/h2>\n\n\n\n<p>Raccogliamo informazioni dall'utente quando visita il nostro sito web, si registra, effettua un ordine, si iscrive alla nostra newsletter, risponde a un sondaggio o compila un modulo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nome \/ Nome utente<\/li>\n\n\n\n<li>Numeri di telefono<\/li>\n\n\n\n<li>Indirizzi e-mail<\/li>\n\n\n\n<li>Indirizzi di posta elettronica<\/li>\n\n\n\n<li>Indirizzi di fatturazione<\/li>\n\n\n\n<li>Et\u00e0<\/li>\n\n\n\n<li>Password<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Come utilizziamo le informazioni raccolte?<\/h2>\n\n\n\n<p>Tutte le informazioni che raccogliamo dall'utente possono essere utilizzate in uno dei seguenti modi:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Per personalizzare la vostra esperienza (le vostre informazioni ci aiutano a rispondere meglio alle vostre esigenze individuali);<\/li>\n\n\n\n<li>Per migliorare il nostro sito web (ci sforziamo continuamente di migliorare le offerte del nostro sito web sulla base delle informazioni e del feedback che riceviamo da voi);<\/li>\n\n\n\n<li>Per migliorare il servizio clienti (le vostre informazioni ci aiutano a rispondere pi\u00f9 efficacemente alle vostre richieste di assistenza e supporto);<\/li>\n\n\n\n<li>Per elaborare le transazioni;<\/li>\n\n\n\n<li>Per gestire un concorso, una promozione, un sondaggio o altre funzioni del sito;<\/li>\n\n\n\n<li>Per inviare e-mail periodiche.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Quando Dapply utilizza le informazioni degli utenti finali provenienti da terzi?<\/h2>\n\n\n\n<p>Dapply raccoglier\u00e0 i dati degli utenti finali necessari per fornire i servizi Dapply ai nostri clienti. Gli utenti finali possono fornirci volontariamente le informazioni che hanno reso disponibili sui siti web dei social media. Se l'utente ci fornisce tali informazioni, possiamo raccogliere le informazioni disponibili pubblicamente dai siti web dei social media indicati dall'utente. L'utente pu\u00f2 controllare la quantit\u00e0 di informazioni rese pubbliche dai siti Web dei social media visitando tali siti e modificando le impostazioni sulla privacy.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quando Dapply utilizza le informazioni sui clienti provenienti da terzi?<\/h2>\n\n\n\n<p>Quando ci contattate, riceviamo alcune informazioni da terzi. Ad esempio, quando ci inviate il vostro indirizzo e-mail per dimostrare interesse a diventare clienti di Dapply, riceviamo informazioni da una terza parte che fornisce servizi di rilevamento automatico delle frodi a Dapply. Occasionalmente raccogliamo anche informazioni rese pubbliche sui siti web dei social media. \u00c8 possibile controllare la quantit\u00e0 di informazioni rese pubbliche dai siti web dei social media visitando questi siti e modificando le impostazioni sulla privacy.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Condividiamo le informazioni raccolte con terze parti?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Possiamo condividere le informazioni che raccogliamo, sia personali che non, con terze parti come inserzionisti, sponsor di concorsi, partner promozionali e di marketing e altri soggetti che forniscono i nostri contenuti o i cui prodotti o servizi riteniamo possano interessarvi. Potremmo anche condividerli con le nostre societ\u00e0 affiliate e i nostri partner commerciali attuali e futuri. Qualora fossimo coinvolti in una fusione, vendita di attivit\u00e0 o altra riorganizzazione aziendale, potremmo condividere o trasferire le vostre informazioni personali e non personali ai nostri successori.<\/li>\n\n\n\n<li>Possiamo ingaggiare fornitori di servizi terzi di fiducia per svolgere funzioni e fornire servizi, come l'hosting e la manutenzione dei nostri server e del sito web, l'archiviazione e la gestione dei database, la gestione delle e-mail, il marketing di archiviazione, l'elaborazione delle carte di credito, l'assistenza clienti e l'evasione degli ordini per i prodotti e i servizi che potete acquistare attraverso il sito web. Probabilmente condivideremo le vostre informazioni personali ed eventualmente alcune non personali con queste terze parti per consentire loro di svolgere questi servizi per noi e per voi.<\/li>\n\n\n\n<li>Possiamo condividere parte dei dati dei nostri file di log, compresi gli indirizzi IP, per scopi analitici con terze parti, quali partner di analisi web, sviluppatori di applicazioni e reti pubblicitarie. Se il vostro indirizzo IP viene condiviso, pu\u00f2 essere utilizzato per stimare la posizione generale e altri dati tecnici come la velocit\u00e0 di connessione, se avete visitato il sito web in un luogo condiviso e il tipo di dispositivo utilizzato per visitarlo. Possono aggregare informazioni sulla nostra pubblicit\u00e0 e su ci\u00f2 che l'utente vede sul sito web e fornire revisioni, ricerche e rapporti per noi e per i nostri inserzionisti.<\/li>\n\n\n\n<li>Possiamo inoltre divulgare informazioni personali e non personali sull'utente a funzionari governativi o delle forze dell'ordine o a parti private, qualora, a nostra esclusiva discrezione, ritenessimo necessario o opportuno rispondere a richieste di risarcimento, procedimenti legali (comprese le citazioni in giudizio) per proteggere i nostri diritti e interessi, o quelli di terzi, la sicurezza del pubblico o di qualsiasi persona, per prevenire o interrompere qualsiasi attivit\u00e0 illegale, non etica o legalmente perseguibile, o per rispettare in altro modo le ordinanze giudiziarie, le leggi, le norme e i regolamenti applicabili.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Come utilizziamo il vostro indirizzo e-mail?<\/h2>\n\n\n\n<p>Inviando il vostro indirizzo e-mail su questo sito web, accettate di ricevere e-mail da parte nostra. \u00c8 possibile annullare la partecipazione a questi elenchi di e-mail facendo clic sul link di opt-out o su altre opzioni di annullamento dell'iscrizione contenute nelle rispettive e-mail. Inviamo e-mail solo a persone che ci hanno autorizzato a contattarle direttamente o tramite terzi. Non inviamo e-mail commerciali non richieste perch\u00e9 odiamo lo spam tanto quanto voi.<\/p>\n\n\n\n<p>Inviando il vostro indirizzo e-mail, accettate anche di consentirci di utilizzare il vostro indirizzo e-mail per il targeting del pubblico dei clienti su siti come Facebook, dove mostriamo pubblicit\u00e0 personalizzata a persone specifiche che hanno scelto di ricevere comunicazioni da noi. Gli indirizzi e-mail inviati solo attraverso la pagina di elaborazione dell'ordine saranno utilizzati per inviare informazioni e aggiornamenti sull'ordine. Tuttavia, se l'utente ci ha fornito lo stesso indirizzo e-mail attraverso un altro metodo, potremo utilizzarlo per uno qualsiasi degli scopi indicati nella presente Informativa. Nota: se in qualsiasi momento si desidera annullare l'iscrizione alla ricezione di future e-mail, sono disponibili istruzioni dettagliate per l'annullamento dell'iscrizione in fondo a ogni e-mail.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Come proteggiamo le vostre informazioni?<\/h2>\n\n\n\n<p>Implementiamo una serie di misure di sicurezza per preservare la sicurezza dei vostri dati personali quando effettuate un ordine o inserite, inviate o accedete ai vostri dati personali. Offriamo l'uso di un server sicuro. Tutte le informazioni sensibili\/creditizie fornite vengono trasmesse tramite la tecnologia Secure Socket Layer (SSL) e poi crittografate nel database dei nostri fornitori di gateway di pagamento per essere accessibili solo da coloro che sono autorizzati con diritti di accesso speciali a tali sistemi e sono tenuti a mantenere le informazioni riservate.<\/p>\n\n\n\n<p>Dopo una transazione, le informazioni private dell'utente (carte di credito, numeri di previdenza sociale, dati finanziari, ecc. Tuttavia, non possiamo assicurare o garantire l'assoluta sicurezza delle informazioni che trasmettete a Dapply o garantire che le vostre informazioni sul Servizio non possano essere accessibili, divulgate, alterate o distrutte a causa di una violazione delle nostre protezioni fisiche, tecniche o gestionali.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le informazioni raccolte attraverso il Servizio Dapply sono sicure?<\/h2>\n\n\n\n<p>Prendiamo precauzioni per proteggere la sicurezza delle vostre informazioni. Disponiamo di procedure fisiche, elettroniche e gestionali per salvaguardare, impedire l'accesso non autorizzato, mantenere la sicurezza dei dati e utilizzare correttamente le vostre informazioni. Tuttavia, n\u00e9 le persone n\u00e9 i sistemi di sicurezza sono infallibili, compresi i sistemi di crittografia.<\/p>\n\n\n\n<p>Inoltre, le persone possono commettere reati intenzionali, commettere errori o non seguire le politiche. Pertanto, pur compiendo sforzi ragionevoli per proteggere le informazioni personali dell'utente, non possiamo garantirne la sicurezza. Se la legge applicabile impone un obbligo non derogabile di protezione delle informazioni personali dell'utente, quest'ultimo accetta che la cattiva condotta intenzionale sar\u00e0 lo standard per misurare la nostra conformit\u00e0 a tale obbligo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Posso aggiornare o correggere le mie informazioni?<\/h2>\n\n\n\n<p>I diritti dell'utente di richiedere aggiornamenti o correzioni alle informazioni raccolte da Dapply dipendono dal suo rapporto con Dapply. Il personale pu\u00f2 aggiornare o correggere le proprie informazioni come indicato nelle nostre politiche aziendali interne sul lavoro.<\/p>\n\n\n\n<p>I clienti hanno il diritto di richiedere la limitazione di alcuni usi e divulgazioni di informazioni di identificazione personale. Potete contattarci per (1) aggiornare o correggere le vostre informazioni di identificazione personale, (2) modificare le vostre preferenze in merito alle comunicazioni e alle altre informazioni che ricevete da noi, o (3) cancellare le informazioni di identificazione personale conservate sui nostri sistemi (in base al paragrafo seguente), cancellando il vostro account. Tali aggiornamenti, correzioni, modifiche e cancellazioni non influiranno sulle altre informazioni che manteniamo o che abbiamo fornito a terzi in base alla presente Informativa sulla privacy prima di tali aggiornamenti, correzioni, modifiche o cancellazioni. Per proteggere la privacy e la sicurezza dell'utente, potremmo adottare misure ragionevoli (come la richiesta di una password unica) per verificare l'identit\u00e0 dell'utente prima di concedergli l'accesso al profilo o di effettuare correzioni. L'utente \u00e8 responsabile del mantenimento della segretezza della propria password unica e delle informazioni relative al proprio account.<\/p>\n\n\n\n<p>L'utente deve essere consapevole del fatto che non \u00e8 tecnologicamente possibile rimuovere dal nostro sistema tutte le informazioni che gli sono state fornite. La necessit\u00e0 di eseguire il backup dei nostri sistemi per proteggere le informazioni da perdite accidentali significa che una copia delle vostre informazioni potrebbe esistere in una forma non cancellabile che sar\u00e0 difficile o impossibile per noi individuare. Subito dopo aver ricevuto la richiesta dell'utente, tutte le informazioni personali memorizzate nei database che utilizziamo attivamente e in altri supporti facilmente consultabili saranno aggiornate, corrette, modificate o eliminate, a seconda dei casi, non appena e nella misura in cui ci\u00f2 sia ragionevolmente e tecnicamente possibile.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Affiliati<\/h2>\n\n\n\n<p>Possiamo divulgare le informazioni (comprese quelle personali) che vi riguardano alle nostre societ\u00e0 affiliate. Ai fini della presente Informativa sulla privacy, per \"Affiliato aziendale\" si intende qualsiasi persona o entit\u00e0 che direttamente o indirettamente controlla o \u00e8 sotto controllo comune con Dapply, sia per propriet\u00e0 che per altro. Le societ\u00e0 affiliate tratteranno le informazioni relative all'utente fornite alle societ\u00e0 affiliate secondo i termini della presente Informativa sulla privacy.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Legge applicabile<\/h2>\n\n\n\n<p>La presente Informativa sulla privacy \u00e8 disciplinata dalle leggi di Cipro, senza tener conto dei conflitti di legge. L'utente acconsente alla giurisdizione esclusiva dei tribunali in relazione a qualsiasi azione o controversia che dovesse insorgere tra le parti ai sensi della presente Informativa sulla privacy o in relazione ad essa.<\/p>\n\n\n\n<p>Il presente Accordo e l'utilizzo del sito web da parte dell'utente sono disciplinati dalle leggi di Cipro, esclusi i conflitti di legge. L'utilizzo del sito web da parte dell'utente pu\u00f2 essere soggetto anche a leggi locali, statali, nazionali o internazionali.<\/p>\n\n\n\n<p>L'utilizzo di Dapply o il contatto diretto con noi implica l'accettazione della presente Informativa sulla privacy. Se l'utente non \u00e8 d'accordo con la presente Informativa sulla privacy, non deve utilizzare il nostro sito web o i nostri servizi. L'uso continuato del sito web, l'impegno diretto con Dapply o la pubblicazione di modifiche alla presente Informativa sulla privacy che non incidono in modo significativo sull'uso o sulla divulgazione dei dati personali dell'utente, implicano l'accettazione di tali modifiche.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Il vostro consenso<\/h2>\n\n\n\n<p>Abbiamo aggiornato la nostra Informativa sulla privacy per fornire una trasparenza completa su ci\u00f2 che viene impostato quando si visita il nostro sito e sul suo utilizzo. Utilizzando il nostro sito web, registrando un account o effettuando acquisti, l'utente acconsente alla nostra Informativa sulla privacy e ne accetta i termini.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Privacy dei bambini<\/h2>\n\n\n\n<p>Non ci rivolgiamo a persone di et\u00e0 inferiore ai 18 anni e non raccogliamo consapevolmente informazioni di identificazione personale da persone di et\u00e0 inferiore ai 18 anni. Se siete un genitore o un tutore e sapete che vostro figlio ci ha fornito dei Dati personali, contattateci. Nel caso in cui venissimo a conoscenza di aver raccolto dati personali da persone di et\u00e0 inferiore ai 18 anni senza aver verificato il consenso dei genitori. In tal caso, rimuoveremo tali informazioni dai nostri server.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Modifiche alla nostra politica sulla privacy<\/h2>\n\n\n\n<p>Potremmo cambiare i nostri Servizi e le nostre politiche e potremmo dover apportare modifiche alla presente Informativa sulla privacy in modo che rifletta accuratamente i nostri Servizi e le nostre politiche. Se non diversamente richiesto dalla legge, vi informeremo (ad esempio, attraverso il nostro Servizio) prima di apportare modifiche alla presente Informativa sulla privacy e vi consentiremo di esaminarle prima che entrino in vigore. In seguito, se continuerete a utilizzare il Servizio, sarete vincolati all'Informativa sulla privacy aggiornata. L'utente pu\u00f2 cancellare il proprio account se non \u00e8 d'accordo con la presente Informativa sulla privacy o con quella aggiornata.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tecnologie di tracciamento<\/h2>\n\n\n\n<p><strong>API di Google Maps<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L'API di Google Maps \u00e8 uno strumento robusto che pu\u00f2 essere utilizzato per creare una mappa personalizzata, una mappa ricercabile, funzioni di check-in, visualizzare dati in tempo reale sincronizzati con la posizione, pianificare percorsi o creare un mashup, solo per citarne alcuni.<\/li>\n\n\n\n<li>Google Maps API pu\u00f2 raccogliere informazioni dall'utente e dal suo dispositivo a fini di sicurezza.<\/li>\n\n\n\n<li>Google Maps API raccoglie le informazioni contenute nella sua Informativa sulla privacy<\/li>\n<\/ul>\n\n\n\n<p><strong>Biscotti<\/strong><\/p>\n\n\n\n<p>Se l'utente proviene dallo Spazio economico europeo (SEE), possiamo raccogliere e utilizzare i suoi dati. In questa sezione della nostra Informativa sulla privacy, spiegheremo esattamente come e perch\u00e9 vengono raccolti questi dati e come li proteggiamo da repliche o usi impropri.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Che cos'\u00e8 il GDPR?<\/h2>\n\n\n\n<p>Il GDPR \u00e8 una legge sulla privacy e sulla protezione dei dati a livello europeo che regola le modalit\u00e0 con cui le aziende proteggono i dati dei residenti dell'UE e migliora il controllo che i residenti dell'UE hanno sui loro dati.<\/p>\n\n\n\n<p>Il GDPR \u00e8 rilevante per qualsiasi azienda che opera a livello globale, non solo per le aziende con sede nell'UE e per i residenti nell'UE. I dati dei nostri clienti sono essenziali indipendentemente dalla loro ubicazione, pertanto abbiamo implementato i controlli del GDPR come standard di base per tutte le nostre attivit\u00e0 in tutto il mondo.<\/p>\n\n\n\n<p>I principi di protezione dei dati includono requisiti quali:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>I dati personali raccolti devono essere trattati in modo equo, legale e trasparente e utilizzati solo nel modo in cui una persona potrebbe ragionevolmente aspettarsi.<\/li>\n\n\n\n<li>I dati personali devono essere raccolti solo per soddisfare uno scopo specifico e devono essere utilizzati solo per tale scopo. Le organizzazioni devono specificare perch\u00e9 hanno bisogno di dati personali quando li raccolgono.<\/li>\n\n\n\n<li>I dati personali non devono essere conservati pi\u00f9 a lungo di quanto sia necessario per raggiungere il loro scopo.<\/li>\n\n\n\n<li>Le persone interessate dal GDPR hanno il diritto di accedere ai propri dati. Possono inoltre richiedere una copia dei propri dati e che questi vengano aggiornati, cancellati, limitati o trasferiti a un'altra organizzazione.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Diritti dell'interessato: Accesso, portabilit\u00e0 e cancellazione dei dati<\/h2>\n\n\n\n<p>Ci impegniamo ad aiutare i nostri clienti a soddisfare i requisiti del GDPR in materia di diritti degli interessati. Dapply elabora o memorizza tutti i dati personali presso fornitori pienamente controllati e conformi al DPA. Conserviamo tutte le conversazioni e i dati personali per un massimo di 6 anni, a meno che il vostro account non venga cancellato. In questo caso, smaltiremo tutti i dati in conformit\u00e0 con i nostri Termini di servizio e la nostra Informativa sulla privacy, ma non li conserveremo per pi\u00f9 di 60 giorni.<\/p>\n\n\n\n<p>Sappiamo che se lavorate con clienti dell'UE, dovete essere in grado di fornire loro la possibilit\u00e0 di accedere, aggiornare, recuperare e rimuovere i dati personali. Vi abbiamo fregati! Siamo stati impostati come self-service e vi abbiamo sempre consentito di accedere ai dati vostri e dei vostri clienti. Il nostro team di assistenza clienti \u00e8 a vostra disposizione per rispondere a qualsiasi domanda sul funzionamento dell'API.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Contattateci<\/h2>\n\n\n\n<p>Per qualsiasi domanda, contattateci:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Via e-mail all'indirizzo <a href=\"mailto:info@dapply.agency\">info@dapply.agency<\/a>;<\/li>\n\n\n\n<li>Per telefono al numero <a href=\"tel:  35724030352\">+35724030352<\/a>;<\/li>\n\n\n\n<li>Oppure tramite il modulo di contatto presente sul sito web: <a href=\"https:\/\/dapply.agency\/it\/get-in-touch\/\">https:\/\/dapply.agency\/get-in-touch\/<\/a>.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Introduction Dapply (\u201cwe,\u201d \u201cour,\u201d or \u201cus\u201d) is committed to protecting your privacy. This Privacy Policy explains how Dapply collects, uses, and discloses your personal information. By accessing or using our Service, you signify that you have read, understood, and agree to our collection, storage, use, and disclosure of your personal information as described in this [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-pages\/policy.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-19","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy policy - Dapply agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dapply.agency\/it\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy policy - Dapply agency\" \/>\n<meta property=\"og:description\" content=\"Introduction Dapply (\u201cwe,\u201d \u201cour,\u201d or \u201cus\u201d) is committed to protecting your privacy. This Privacy Policy explains how Dapply collects, uses, and discloses your personal information. By accessing or using our Service, you signify that you have read, understood, and agree to our collection, storage, use, and disclosure of your personal information as described in this [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dapply.agency\/it\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Dapply agency\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-24T07:42:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dapply.agency\/privacy-policy\/\",\"url\":\"https:\/\/dapply.agency\/privacy-policy\/\",\"name\":\"Privacy policy - Dapply agency\",\"isPartOf\":{\"@id\":\"https:\/\/dapply.agency\/#website\"},\"datePublished\":\"2024-05-31T09:59:57+00:00\",\"dateModified\":\"2024-06-24T07:42:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dapply.agency\/privacy-policy\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dapply.agency\/privacy-policy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dapply.agency\/privacy-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dapply.agency\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dapply.agency\/#website\",\"url\":\"https:\/\/dapply.agency\/\",\"name\":\"Dapply agency\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dapply.agency\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy policy - Dapply agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dapply.agency\/it\/privacy-policy\/","og_locale":"it_IT","og_type":"article","og_title":"Privacy policy - Dapply agency","og_description":"Introduction Dapply (\u201cwe,\u201d \u201cour,\u201d or \u201cus\u201d) is committed to protecting your privacy. This Privacy Policy explains how Dapply collects, uses, and discloses your personal information. By accessing or using our Service, you signify that you have read, understood, and agree to our collection, storage, use, and disclosure of your personal information as described in this [&hellip;]","og_url":"https:\/\/dapply.agency\/it\/privacy-policy\/","og_site_name":"Dapply agency","article_modified_time":"2024-06-24T07:42:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dapply.agency\/privacy-policy\/","url":"https:\/\/dapply.agency\/privacy-policy\/","name":"Privacy policy - Dapply agency","isPartOf":{"@id":"https:\/\/dapply.agency\/#website"},"datePublished":"2024-05-31T09:59:57+00:00","dateModified":"2024-06-24T07:42:25+00:00","breadcrumb":{"@id":"https:\/\/dapply.agency\/privacy-policy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dapply.agency\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dapply.agency\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dapply.agency\/"},{"@type":"ListItem","position":2,"name":"Privacy policy"}]},{"@type":"WebSite","@id":"https:\/\/dapply.agency\/#website","url":"https:\/\/dapply.agency\/","name":"Dapply agency","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dapply.agency\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/dapply.agency\/it\/wp-json\/wp\/v2\/pages\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dapply.agency\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dapply.agency\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dapply.agency\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dapply.agency\/it\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":4,"href":"https:\/\/dapply.agency\/it\/wp-json\/wp\/v2\/pages\/19\/revisions"}],"predecessor-version":[{"id":312,"href":"https:\/\/dapply.agency\/it\/wp-json\/wp\/v2\/pages\/19\/revisions\/312"}],"wp:attachment":[{"href":"https:\/\/dapply.agency\/it\/wp-json\/wp\/v2\/media?parent=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}